{"id":12726,"date":"2021-05-18T10:07:14","date_gmt":"2021-05-18T10:07:14","guid":{"rendered":"https:\/\/www.oliveoilathome.com\/conditions-dachat-en-ligne\/"},"modified":"2022-08-31T10:31:54","modified_gmt":"2022-08-31T10:31:54","slug":"conditions-dachat-en-ligne","status":"publish","type":"page","link":"https:\/\/www.oliveoilathome.com\/fr\/conditions-dachat-en-ligne\/","title":{"rendered":"Conditions d&#8217;achat en ligne"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Conditions d&#8217;achat en ligne&#8221; font_container=&#8221;tag:h1|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;]<div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><strong><u>PROC\u00c9DURE POUR PASSER DES COMMANDES<\/u><\/strong><\/p>\n<p><strong>SERVICE D\u2019ATTENTION AU CLIENT:<\/strong><\/p>\n<ul>\n<li><strong>E-mail<\/strong>: <a href=\"mailto:contacto@oleofer.com\">contacto@oleofer.com<\/a><\/li>\n<li><strong>Web<\/strong>: <a href=\"https:\/\/www.oliveoilathome.com\/fr\/\">oliveoilathome.com<\/a><\/li>\n<\/ul>\n<p><strong>CONDITIONS D&#8217;ACHAT EN LIGNE<\/strong><\/p>\n<p>Tous les achats effectu\u00e9s via le portail www.miaceiteadomicilio.com (ci-apr\u00e8s <em>le Web<\/em>), propri\u00e9t\u00e9 de OLEOFER, S.L., sont soumis aux conditions g\u00e9n\u00e9rales contenues dans les mentions l\u00e9gales. Les conditions g\u00e9n\u00e9rales pr\u00e9valent sur les conditions d&#8217;achat en ligne.<\/p>\n<p>Tous les produits et services sont soumis aux conditions expliqu\u00e9es ci-dessous. En achetant sur le Web, vous acceptez automatiquement ces conditions. Veuillez les lire attentivement.<\/p>\n<p>Ces conditions constituent compl\u00e8tement l&#8217;accord entre les parties concernant les transactions de vente en ligne entre OLEOFER, S.L. et ses clients.<\/p>\n<p>OLEOFER, S.L. est autoris\u00e9e \u00e0 modifier unilat\u00e9ralement chacune des obligations \u00e9nonc\u00e9es dans ces conditions, sans pr\u00e9avis. De m\u00eame, elle est habilit\u00e9e de restructurer, modifier ou supprimer toute information, service ou contenu inclus dans le Web, sans pr\u00e9avis.<\/p>\n<p>Un achat ser\u00e1 consid\u00e9r\u00e9 d\u00e9finitif une fois qu&#8217;il ait accept\u00e9 par OLEOFER, S.L.<\/p>\n<p>OLEOFER, S.L. se r\u00e9serve le droit d&#8217;admission et d&#8217;annulation de toute commande, pouvant rembourser le montant pay\u00e9 par le client et \u00e9tant exon\u00e9r\u00e9 de toute autre obligation.<\/p>\n<p><strong>LISTE DES PRIX<\/strong><\/p>\n<p>Le prix des produits est indiqu\u00e9 en EUROS et comprend les taxes \u00e9tablies selon les dispositions l\u00e9gales en Espagne. Dans le r\u00e9sum\u00e9 final de la commande, vous verrez le prix final ou total de l&#8217;achat, qui indique le montant correspondant au prix du produit concret et le montant correspondant aux taxes applicables.<\/p>\n<p>En raison de sa politique commerciale, OLEOFER, S.L. pourra r\u00e9aliser des variations finales de prix soit pour la fid\u00e9lit\u00e9, pour l&#8217;acquisition de produits d&#8217;une certaine entit\u00e9 ou pertinence, soit pour d\u2019autres motifs qu\u2019OLEOFER, S.L. pourra d\u00e9terminer en temps voulu. N\u00e9anmoins, OLEOFER, S.L. pourra librement et volontairement offrir ces r\u00e9ductions et\/ou rabais suivant son propre crit\u00e8re, sans que ceux-ci peuvent \u00eatre exig\u00e9s ou demand\u00e9s par le client \u00e0 aucun moment.<\/p>\n<p>Les prix indiqu\u00e9s n&#8217;incluent pas les frais de livraison. Les prix sont valables sauf faute de frappe. Les produits sont disponibles \u00e0 la vente jusqu&#8217;\u00e0 la rupture des stocks.<\/p>\n<p>OLEOFER, S.L. se r\u00e9serve le droit de r\u00e9viser et modifier les prix indiqu\u00e9s \u00e0 tout moment.<\/p>\n<p>Une fois v\u00e9rifi\u00e9 le paiement, OLEOFER, S.L. commencera le traitement de la commande.<\/p>\n<p><span id=\"anchor-reglement\"><strong>R\u00c8GLEMENT<\/strong><\/span><\/p>\n<p>Une fois que vous acc\u00e9dez \u00e0 votre compte, vous verrez votre panier. En cliquant sur \u00ab Confirmer la commande \u00bb, vous irez \u00e0 la section d\u2019Exp\u00e9dition et paiement. Dans cette section, vous devez pr\u00e9ciser si vous souhaitez que la commande soit envoy\u00e9e \u00e0 votre adresse d&#8217;enregistrement ou \u00e0 une adresse diff\u00e9rente. Ensuite, vous devez effectuer le paiement selon la modalit\u00e9 choisie, en cliquant sur \u00ab Finaliser la commande &#8211; Ordre de paiement obligatoire \u00bb. Une fois que le paiement est effectu\u00e9, vous verrez la confirmation d&#8217;enregistrement de la commande et vous recevrez imm\u00e9diatement cette confirmation dans votre e-mail.<\/p>\n<p>La facture correspondante inclura les renseignements fournis \u00e0 cet effet, et ser\u00e1 \u00e9mise une fois que la r\u00e9ception du paiement est confirm\u00e9e et la commande a \u00e9t\u00e9 trait\u00e9e. Vous pouvez obtenir la facture avec la commande.<\/p>\n<p>Le processus de paiement pour l&#8217;huile d\u2019olive et les produits que vous avez choisi d&#8217;acheter est tr\u00e8s simple. Une fois que vous avez termin\u00e9 avec votre panier, cliquez sur l&#8217;\u00e9tape suivante et vous pourrez choisir une des options de paiement propos\u00e9es ci-dessous:<\/p>\n<ul>\n<li>Via une passerelle de paiement par carte Redsys.<\/li>\n<li>Par PayPal (le moyen de paiement le plus s\u00e9curis\u00e9 sur Internet) ou par carte de cr\u00e9dit. Si vous choisissez cette option, vous serez transf\u00e9r\u00e9 vers l&#8217;environnement PayPal pour finaliser votre paiement. Une fois que vous acc\u00e9dez \u00e0 l&#8217;environnement PayPal, vous aurez la possibilit\u00e9 de payer via un compte PayPal ou \u00e0 travers de votre carte de cr\u00e9dit, sans besoin d\u2019\u00eatre enregistr\u00e9 sur la plateforme PayPal, en choisissant l&#8217;option marqu\u00e9e dans l&#8217;image suivante qui se trouve \u00e0 droite en bas. \u00c0 partir de l\u00e0, PayPal vous demandera les renseignements de votre carte de cr\u00e9dit pour terminer le processus de paiement.<\/li>\n<li>Par virement bancaire. Veuillez indiquer le num\u00e9ro de commande comme r\u00e9f\u00e9rence de paiement. Votre commande sera trait\u00e9e uniquement \u00e0 la suite de la r\u00e9ception du montant \u00e0 notre compte.<\/li>\n<li>Bizum<\/li>\n<\/ul>\n<p><strong>EXP\u00c9DITION<\/strong><\/p>\n<p>OLEOFER, S.L. n&#8217;enverra aucun produit jusque le D\u00e9partement d\u2019administration n&#8217;aura pas v\u00e9rifi\u00e9 que le paiement a \u00e9t\u00e9 effectu\u00e9.<\/p>\n<p>La livraison sera consid\u00e9r\u00e9e comme effectu\u00e9e lorsque le transporteur aura mis les produits \u00e0 disposition du client et le client aura sign\u00e9 le bon de livraison. Il appartient au client de v\u00e9rifier les produits \u00e0 leur r\u00e9ception et de noter dans le bon de livraison toutes les anomalies et r\u00e9clamations qui pourraient \u00eatre justifi\u00e9es.<\/p>\n<p>Pour l\u2019exp\u00e9dition des produits OLEOFER, S.L. utilisera les moyens qu&#8217;elle jugera appropri\u00e9s afin de remplir ses engagements.<\/p>\n<p><em>FRAIS D&#8217;ENVOI:<\/em><\/p>\n<table width=\"348\">\n<tbody>\n<tr>\n<td width=\"252\">De 0,1 \u00e0 5 Kg<\/td>\n<td width=\"96\">11,95 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"252\">De 5,1 \u00e0 10 Kg<\/td>\n<td width=\"96\">16,95 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"252\">De 10,1 \u00e0 15 Kg<\/td>\n<td width=\"96\">21,95 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"252\">De 15,1 \u00e0 20 Kg<\/td>\n<td width=\"96\">25,95 \u20ac<\/td>\n<\/tr>\n<tr>\n<td width=\"252\">De 20,1 \u00e0 30 Kg<\/td>\n<td width=\"96\">34,95 \u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Cependant, OLEOFER, S.L. SE R\u00c9SERVE LE DROIT DE DEMANDER UNE QUANTIT\u00c9 SUPPL\u00c9MENTAIRE pour des commandes particuli\u00e8rement lourdes ou volumineuses. Dans le cas o\u00f9 cela se produirait et le client ne serait pas int\u00e9ress\u00e9 \u00e0 formaliser la commande en versant les frais d\u2019envoi indiqu\u00e9s, le montant pay\u00e9 lui sera rembours\u00e9 et la commande sera annul\u00e9e. OLEOFER, S.L. sera lib\u00e9r\u00e9e de tout autre engagement ou obligation envers le client.<\/p>\n<p><span id=\"anchor-livraison\"><em>D\u00c9LAI DE LIVRAISON<\/em><\/span><\/p>\n<p>En r\u00e8gle g\u00e9n\u00e9rale, une commande est exp\u00e9di\u00e9e (quitte nos locaux pour destination) le jour ouvrable suivant la r\u00e9ception du paiement. La livraison \u00e0 destination sera effectu\u00e9e en fonction de la zone de destination. Le d\u00e9lai moyen de livraison est de 3 \u00e0 5 jours ouvr\u00e9s. Cependant, ces d\u00e9lais ne sont qu\u2019indicatifs et peuvent varier pour des raisons ind\u00e9pendantes de la volont\u00e9 de notre entreprise. OLEOFER, S.L. ne s&#8217;engage sur aucun d\u00e9lai de livraison sp\u00e9cifique, car le processus d&#8217;exp\u00e9dition d\u00e9pend de tiers.<\/p>\n<p>Si une livraison prendra plus de 7 jours ouvr\u00e9, OLEOFER, S.L. contactera le client pour le notifier et lui donner la possibilit\u00e9 d&#8217;annuler la commande et de r\u00e9cup\u00e9rer son argent imm\u00e9diatement par virement bancaire.<\/p>\n<p>Chaque envoi inclura une copie du bon de livraison d\u00e9taillant la marchandise contenue dans la commande. Le destinataire est tenu de v\u00e9rifier que le num\u00e9ro de sa commande et celui dudit bon de livraison correspondent. De m\u00eame, il faut v\u00e9rifier que le nombre de paquets figurant sur le document de livraison du transporteur co\u00efncide avec le nombre de paquets livr\u00e9s.<\/p>\n<p>Lors de la livraison de la marchandise, le client doit signer le bon de livraison en gage de conformit\u00e9 avec la livraison effectu\u00e9e. L&#8217;accord du client sur le bon de livraison implique la renonciation \u00e0 tout type de r\u00e9clamation ou plainte concernant la marchandise command\u00e9e et re\u00e7ue.<\/p>\n<p>Lors du voyage jusqu&#8217;\u00e0 sa destination la marchandise est enti\u00e8rement assur\u00e9e par OLEOFER, S.L. Le co\u00fbt de ladite assurance est inclus dans le prix correspondant \u00e0 la rubrique de fret.<\/p>\n<p>Autant pour rendre l&#8217;assurance effective que pour corriger toute erreur de livraison, il est indispensable que tout incident concernant la marchandise re\u00e7ue ou son emballage soit consign\u00e9 dans la rubrique \u00ab Observations \u00bb du document de livraison du transporteur. Il est \u00e9galement essentiel que vous communiquiez \u00e0 OLEOFER, S.L. ledit incident dans un d\u00e9lai maximum de 24 heures.<\/p>\n<p>Si ces conditions ne sont pas remplies, OLEOFER, S.L. n&#8217;assumera aucune responsabilit\u00e9 pour ladite marchandise.<\/p>\n<p><strong>\u00a0<\/strong><em>RUPTURE DE STOCK<\/em><\/p>\n<p>Touts les produits offerts sur le Web sont des produits en stock, soit dans notre propre entrep\u00f4t, soit dans celui d&#8217;une entit\u00e9, d&#8217;un fabricant ou d&#8217;un grossiste, ce qui nous permet de servir le produit dans le d\u00e9lai signal\u00e9 comme d\u00e9lai de livraison. Cependant, la synchronisation du web avec les entrep\u00f4ts n&#8217;est pas instantan\u00e9e. De plus, dans le laps de temps entre le moment o\u00f9 un client enregistre une commande sur le Web jusqu&#8217;\u00e0 ce que nous recevions et traitions la preuve de paiement, certains produits pourraient \u00eatre \u00e9puis\u00e9s. Par cons\u00e9quent, il peut y avoir des cas isol\u00e9s dans lesquels nous ne pouvons pas traiter une commande \u00e0 cause d&#8217;un manque de stock.<\/p>\n<p>Lorsqu&#8217;il n&#8217;est pas possible de servir un produit \u00e0 cause d&#8217;un manque de stock, OLEOFER, S.L. contactera le client pour le notifier, annuler la commande et lui rembours\u00e9 imm\u00e9diatement son argent par virement bancaire.<\/p>\n<p>Dans ces cas, le montant sera toujours rembours\u00e9 au client et la commande sera annul\u00e9e. IL NE SERA PAS POSSIBLE DE GARDER LE PRIX DU PRODUIT VENDU POUR LE SERVIR LORSQUE LE STOCK EST REMPLAC\u00c9, car le prix des produits change \u00e0 chaque remplacement en fonction de notre prix d&#8217;achat.<\/p>\n<p><span id=\"anchor-garantie\"><strong>GARANTIE<\/strong><\/span><\/p>\n<p><strong>\u00a0<\/strong>Les produits n&#8217;ont pas de garanties suppl\u00e9mentaires car ceux sont des produits exquis, d&#8217;\u00e9laboration artisanale et p\u00e9rissables, c&#8217;est-\u00e0-dire qu\u2019ils sont pr\u00e9vus pour une consommation imm\u00e9diate. Donc, la fra\u00eecheur et le bon \u00e9tat sont garantis au moment de la livraison. Du coup, OLEOFER, S.L. n&#8217;est pas responsable de la conservation, du traitement ou de la distribution que le client ou l&#8217;utilisateur pourrait leur donner une fois qu&#8217;ils sont livr\u00e9s.<\/p>\n<p>Nos produits sont avalis\u00e9s par les organismes de certification de qualit\u00e9 les plus repr\u00e9sentatifs de notre secteur.<strong>\u00a0<\/strong><\/p>\n<p><strong>RETOURS ET REMBOURSEMENTS<\/strong><\/p>\n<p>\u00ab Oliveoilathome \u00bb offre pleine garantie de tous les produits vendus dans sa boutique en ligne. N\u00e9anmoins, si vous n&#8217;\u00eates pas compl\u00e8tement satisfait du produit achet\u00e9, nous vous l&#8217;\u00e9changerons ou vous rembourserons le montant pay\u00e9.<\/p>\n<p><strong><u>Comment exercer le droit de r\u00e9tractation:<\/u><\/strong> Pour exercer le droit de r\u00e9tractation \u00e0 l&#8217;\u00e9gard des produits achet\u00e9s exclusivement sur le Web, vous devez communiquer votre d\u00e9cision incontestable de r\u00e9silier le contrat dans un d\u00e9lai de 14 jours calendaires, de l&#8217;une des mani\u00e8res suivantes:<\/p>\n<ul>\n<li>Si vous choisissez l&#8217;option de retourner le produit dans l&#8217;un des magasins d\u2019OLEOFER, S.L., vous devez d&#8217;abord contacter notre service client, qui vous enverra une autorisation de retour que vous devrez pr\u00e9senter au magasin.<\/li>\n<li>Si vous choisissez l&#8217;option de retourner le produit via la boutique en ligne du site Web, vous devez contacter notre service client par email \u00e0 l\u2019adresse <u>contacto@oleofer.com<\/u> pour communiquer d\u2019une mani\u00e8re claire votre d\u00e9cision de r\u00e9silier le contrat.<\/li>\n<li>Sans pr\u00e9judice des dispositions des points pr\u00e9c\u00e9dents, vous pouvez \u00e9galement choisir d&#8217;exercer votre droit de r\u00e9tractation en compl\u00e9tant et en envoyant par un email \u00e0 l\u2019adresse\u00a0<u>contacto@oleofer.com<\/u> le formulaire de r\u00e9tractation que vous pouvez demander au m\u00eame compte \u00e9lectronique, auquel cas nous vous confirmerons sans d\u00e9lai par la m\u00eame voie la r\u00e9ception de ladite r\u00e9tractation.<\/li>\n<\/ul>\n<p>Le droit de r\u00e9tractation sera consid\u00e9r\u00e9 comme \u00e9tant exerc\u00e9 en temps voulu lorsque vous nous aurez transmis la communication relative \u00e0 cet exercice avant la fin du d\u00e9lai correspondant, dans les conditions indiqu\u00e9es ci-dessus. <strong>Cons\u00e9quences de la r\u00e9tractation:<\/strong> Dans le cas o\u00f9 vous exercez le droit de r\u00e9tractation, nous vous rembourserons tous les paiements que nous aurons re\u00e7us de votre part, \u00e0 l&#8217;exclusion des frais de livraison, sans retard injustifi\u00e9 et, dans tous les cas, au plus tard 14 jours calendaires \u00e0 compter de la date sur laquelle vous nous informez de votre d\u00e9cision de r\u00e9silier le contrat. Nous proc\u00e9derons \u00e0 ce remboursement en utilisant le m\u00eame moyen de r\u00e8glement dans lequel l&#8217;achat a \u00e9t\u00e9 effectu\u00e9 sans encourir de frais \u00e0 cause du remboursement, \u00e0 l&#8217;exception des frais de retour du produit.<strong>\u00a0<\/strong><\/p>\n<p><strong>RECLAMATIONS<\/strong><\/p>\n<p>Il y a des lettres de r\u00e9clamation \u00e0 la disposition de nos clients. Le formulaire peut \u00eatre demand\u00e9 \u00e0 notre service client par t\u00e9l\u00e9phone ou par email, et nous vous le ferons parvenir \u00e0 l&#8217;adresse que vous indiquez. Vous pouvez \u00e9galement en faire la demande dans nos \u00e9tablissements, dans la boutique situ\u00e9e \u00e0 CTRA. PUENTE DE G\u00c9NAVE, LA PUERTA DE SEGURA KM 0,300 &#8211; 23360 LA PUERTA DE SEGURA (JA\u00c9N).<\/p>\n<p>En outre, la Commission europ\u00e9enne a facilit\u00e9 une plateforme de r\u00e9solution des litiges en ligne, disponible sur le lien suivant : <a href=\"http:\/\/ec.europa.eu\/consumers\/odr\/\">http:\/\/ec.europa.eu\/consumers\/odr\/<\/a>. Les consommateurs pourront d\u00e9poser leurs r\u00e9clamations via la plateforme de r\u00e9solution des litiges en ligne.<strong>\u00a0<\/strong><\/p>\n<p><strong>JURISDICTION, COMPETENCE ET LOI<\/strong><\/p>\n<p><em><u>Option 1 :<\/u><\/em><\/p>\n<p>Pour la r\u00e9solution des conflits les parties se soumettent aux cours et tribunaux du domicile de OLEOFER, S.L., renonciant \u00e0 toute autre juridiction qui pourrait leur correspondre. En ce qui concerne les questions de fond d\u00e9coulant de l\u2019observation \/ non-observation des conditions convenues, elles seront r\u00e9gies en premier lieu par ce qui y est convenu et subsidiairement par les dispositions du Code civil et de la l\u00e9gislation compl\u00e9mentaire applicable au cas.<\/p>\n<p><em><u>Option 2:<\/u><\/em><\/p>\n<p>Les parties soumettent les questions de jurisdiction et de comp\u00e9tence aux dispositions de la Loi 1\/2000 du 7 janvier sur la proc\u00e9dure civile. En ce qui concerne les questions de fond d\u00e9coulant de l\u2019observation \/ non-observation des conditions convenues, elles seront r\u00e9gies en premier lieu par ce qui y est convenu et subsidiairement par les dispositions du Code civil et de la l\u00e9gislation compl\u00e9mentaire applicable au cas.<\/p>\n<p><strong>FORMULAIRE DE RETRAIT<\/strong><\/p>\n<p>Si vous souhaitez exercer votre droit de r\u00e9tractation pour un ou plusieurs produits de cette commande, n\u2019oubliez pas que vous pouvez faire des d\u00e9marches correspondantes dans un d\u00e9lai de 14 jours \u00e0 compter du moment de la livraison, en effectuant le retour dans quelconque de nos magasins physiques ou en compl\u00e9tant ce formulaire et l\u2019envoyant \u00e0 <a href=\"mailto:contacto@oleofer.com\">contacto@oleofer.com<\/a>.<\/p>\n<p>&#8211; <strong>\u00c0 l&#8217;attention de<\/strong> (consignez le nom complet de l&#8217;entreprise et l&#8217;adresse compl\u00e8te que vous trouverez sur la facture) :<\/p>\n<p><strong>\u2013 <\/strong><strong>Je\/nous vous informe\/informons par la pr\u00e9sente que je\/nous r\u00e9silie\/r\u00e9silions de mon\/notre contrat de vente du bien\/de la prestation du service suivant<\/strong> (indiquez le\/les bien(s) ou service(s) acquis) :<\/p>\n<p><strong>\u2013 <\/strong><strong>Commande envoy\u00e9e\/re\u00e7ue le<\/strong> (indiquez la date de la commande et\/ou la reception), <strong>dont le num\u00e9ro de facture\/commande<\/strong> <strong>est comme suit <\/strong>(indiquez le num\u00e9ro de facture\/commande) :<\/p>\n<p><strong>Date de commande\/date de r\u00e9ception :<\/strong><\/p>\n<p><strong>Num\u00e9ro de commande\/facture :<\/strong><\/p>\n<p>&#8211; <strong>Afin d&#8217;exercer efficacement mon droit de r\u00e9tractation, j&#8217;effectuerai le retour du\/ des produit(s) via l&#8217;une des options suivantes<\/strong> (marquez d&#8217;un \u00ab X \u00bb l&#8217;option choisie)* :<\/p>\n<p><strong>Moyennant livraison \u00e0 l&#8217;\u00e9tablissement.<\/strong><\/p>\n<p>Moyennant un ramassage \u00e0 mon domicile, auquel cas le ramassage aura un co\u00fbt identique au co\u00fbt d&#8217;exp\u00e9dition du produit et sera d\u00e9duit du montant \u00e0 rembourser pour le retrait de l&#8217;achat (le co\u00fbt du retrait sera compris entre _______ EUR et ________ EUR, selon le type de produit).<\/p>\n<p><strong>\u2013 <\/strong><strong>Nom et adresse du\/des consommateur(s) et utilisateur(s) <\/strong>(indiquez le nom, l&#8217;adresse et l&#8217;identifiant, tels qu&#8217;ils apparaissent sur la facture d&#8217;achat) :<\/p>\n<p><strong>Signature :\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0\u00a0\u00a0 Date :<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>* OLEOFER, S.L. &#8220;TIERRAS DE T\u00c1VARA&#8221; vous rappelle que, conform\u00e9ment \u00e0 l&#8217;article 108 du D\u00e9cret L\u00e9gislatif Royal 1\/2007, du 16 novembre, qui approuve le texte r\u00e9vis\u00e9 de la Loi G\u00e9n\u00e9rale pour la D\u00e9fense des Consommateurs et des Utilisateurs et d&#8217;autres lois compl\u00e9mentaires, le consommateur a un d\u00e9lai de 14 jours (\u00e0 compter de la date de communication de l&#8217;exercice du droit de r\u00e9tractation) pour livrer les produits soumis \u00e0 r\u00e9tractation.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_custom_heading text=\"Conditions d'achat en ligne\" font_container=\"tag:h1|text_align:left\" use_theme_fonts=\"yes\"]PROC\u00c9DURE POUR PASSER DES COMMANDES SERVICE D\u2019ATTENTION AU CLIENT: E-mail: contacto@oleofer.com Web: oliveoilathome.com CONDITIONS D&#8217;ACHAT EN LIGNE Tous les achats effectu\u00e9s via le portail www.miaceiteadomicilio.com (ci-apr\u00e8s le Web), propri\u00e9t\u00e9 de OLEOFER, S.L., sont soumis aux conditions g\u00e9n\u00e9rales contenues dans les mentions l\u00e9gales. Les conditions g\u00e9n\u00e9rales pr\u00e9valent sur les conditions...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":30,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"class_list":["post-12726","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conditions d&#039;achat en ligne | Olive Oil at Home<\/title>\n<meta name=\"description\" content=\"Politique de confidentialit\u00e9 \u2705 Produit \u00e9cologique \u2705 S\u00e9lection Gourmande \u2705 Origine Ja\u00e9n \u2705 Votre huile \u00e0 la maison\" \/>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conditions d&#039;achat en ligne | Olive Oil at Home\" \/>\n<meta property=\"og:description\" content=\"Politique de confidentialit\u00e9 \u2705 Produit \u00e9cologique \u2705 S\u00e9lection Gourmande \u2705 Origine Ja\u00e9n \u2705 Votre huile \u00e0 la maison\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oliveoilathome.com\/fr\/conditions-dachat-en-ligne\/\" \/>\n<meta property=\"og:site_name\" content=\"Olive Oil at Home\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tierrasdetavara\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T10:31:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Tierrasdetavara\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/conditions-dachat-en-ligne\\\/\",\"url\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/conditions-dachat-en-ligne\\\/\",\"name\":\"Conditions d'achat en ligne | Olive Oil at Home\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/#website\"},\"datePublished\":\"2021-05-18T10:07:14+00:00\",\"dateModified\":\"2022-08-31T10:31:54+00:00\",\"description\":\"Politique de confidentialit\u00e9 \u2705 Produit \u00e9cologique \u2705 S\u00e9lection Gourmande \u2705 Origine Ja\u00e9n \u2705 Votre huile \u00e0 la maison\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/conditions-dachat-en-ligne\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/conditions-dachat-en-ligne\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/conditions-dachat-en-ligne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conditions d&#8217;achat en ligne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/\",\"name\":\"Olive Oil at Home\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/#organization\",\"name\":\"Olive Oil At Home\",\"url\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.oliveoilathome.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.oliveoilathome.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo.jpg\",\"width\":400,\"height\":91,\"caption\":\"Olive Oil At Home\"},\"image\":{\"@id\":\"https:\\\/\\\/www.oliveoilathome.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tierrasdetavara\",\"https:\\\/\\\/x.com\\\/Tierrasdetavara\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions d'achat en ligne | Olive Oil at Home","description":"Politique de confidentialit\u00e9 \u2705 Produit \u00e9cologique \u2705 S\u00e9lection Gourmande \u2705 Origine Ja\u00e9n \u2705 Votre huile \u00e0 la maison","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Conditions d'achat en ligne | Olive Oil at Home","og_description":"Politique de confidentialit\u00e9 \u2705 Produit \u00e9cologique \u2705 S\u00e9lection Gourmande \u2705 Origine Ja\u00e9n \u2705 Votre huile \u00e0 la maison","og_url":"https:\/\/www.oliveoilathome.com\/fr\/conditions-dachat-en-ligne\/","og_site_name":"Olive Oil at Home","article_publisher":"https:\/\/www.facebook.com\/tierrasdetavara","article_modified_time":"2022-08-31T10:31:54+00:00","twitter_card":"summary_large_image","twitter_site":"@Tierrasdetavara","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.oliveoilathome.com\/fr\/conditions-dachat-en-ligne\/","url":"https:\/\/www.oliveoilathome.com\/fr\/conditions-dachat-en-ligne\/","name":"Conditions d'achat en ligne | Olive Oil at Home","isPartOf":{"@id":"https:\/\/www.oliveoilathome.com\/fr\/#website"},"datePublished":"2021-05-18T10:07:14+00:00","dateModified":"2022-08-31T10:31:54+00:00","description":"Politique de confidentialit\u00e9 \u2705 Produit \u00e9cologique \u2705 S\u00e9lection Gourmande \u2705 Origine Ja\u00e9n \u2705 Votre huile \u00e0 la maison","breadcrumb":{"@id":"https:\/\/www.oliveoilathome.com\/fr\/conditions-dachat-en-ligne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oliveoilathome.com\/fr\/conditions-dachat-en-ligne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.oliveoilathome.com\/fr\/conditions-dachat-en-ligne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.oliveoilathome.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Conditions d&#8217;achat en ligne"}]},{"@type":"WebSite","@id":"https:\/\/www.oliveoilathome.com\/fr\/#website","url":"https:\/\/www.oliveoilathome.com\/fr\/","name":"Olive Oil at Home","description":"","publisher":{"@id":"https:\/\/www.oliveoilathome.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oliveoilathome.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.oliveoilathome.com\/fr\/#organization","name":"Olive Oil At Home","url":"https:\/\/www.oliveoilathome.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.oliveoilathome.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.oliveoilathome.com\/wp-content\/uploads\/2021\/04\/logo.jpg","contentUrl":"https:\/\/www.oliveoilathome.com\/wp-content\/uploads\/2021\/04\/logo.jpg","width":400,"height":91,"caption":"Olive Oil At Home"},"image":{"@id":"https:\/\/www.oliveoilathome.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tierrasdetavara","https:\/\/x.com\/Tierrasdetavara"]}]}},"_links":{"self":[{"href":"https:\/\/www.oliveoilathome.com\/fr\/wp-json\/wp\/v2\/pages\/12726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oliveoilathome.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.oliveoilathome.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.oliveoilathome.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oliveoilathome.com\/fr\/wp-json\/wp\/v2\/comments?post=12726"}],"version-history":[{"count":14,"href":"https:\/\/www.oliveoilathome.com\/fr\/wp-json\/wp\/v2\/pages\/12726\/revisions"}],"predecessor-version":[{"id":13261,"href":"https:\/\/www.oliveoilathome.com\/fr\/wp-json\/wp\/v2\/pages\/12726\/revisions\/13261"}],"wp:attachment":[{"href":"https:\/\/www.oliveoilathome.com\/fr\/wp-json\/wp\/v2\/media?parent=12726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}